{"id":80770,"date":"2021-05-28T08:41:58","date_gmt":"2021-05-28T08:41:58","guid":{"rendered":"https:\/\/www.stellarinfo.com\/blog\/?p=80770"},"modified":"2023-04-20T03:32:25","modified_gmt":"2023-04-20T03:32:25","slug":"comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange","status":"publish","type":"post","link":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/","title":{"rendered":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><?xml encoding=\"utf-8\" ?><p class=\"wp-block-paragraph\">La r&eacute;cup&eacute;ration de la base de donn&eacute;es Exchange (EDB) est souvent n&eacute;cessaire lorsque la base de donn&eacute;es est d&eacute;mont&eacute;e du serveur ou devient inaccessible. Cela peut se produire pour plusieurs raisons, telles qu&rsquo;un crash du serveur, un arr&ecirc;t forc&eacute; ou brutal, une intrusion de virus ou de logiciels malveillants, ou encore une d&eacute;faillance logicielle ou mat&eacute;rielle. La r&eacute;cup&eacute;ration d&rsquo;une base de donn&eacute;es corrompue ou endommag&eacute;e peut &ecirc;tre une situation d&eacute;licate, selon le niveau de dommage. Dans Exchange Server, Microsoft fournit un outil en ligne de commande natif appel&eacute; EseUtil qui permet de v&eacute;rifier l&rsquo;&eacute;tat d&rsquo;une base de donn&eacute;es et d&rsquo;effectuer une r&eacute;cup&eacute;ration douce ou mat&eacute;rielle. Il permet &eacute;galement de restaurer un fichier EDB pour la <strong>r&eacute;cup&eacute;ration des tonalit&eacute;s<\/strong> et des bases de donn&eacute;es de r&eacute;cup&eacute;ration (RDB)<a href=\"https:\/\/www.stellarinfo.com\/article\/create-recovery-database-in-exchange-server.php\">.<\/a><\/p><p class=\"wp-block-paragraph\">La r&eacute;cup&eacute;ration mat&eacute;rielle est n&eacute;cessaire lorsque la r&eacute;cup&eacute;ration logicielle ne parvient pas &agrave; r&eacute;parer la base de donn&eacute;es sur le serveur. Cependant, avec la r&eacute;cup&eacute;ration mat&eacute;rielle, vous devez accepter la perte de donn&eacute;es car ce processus purge d&eacute;finitivement toutes les donn&eacute;es corrompues ou irr&eacute;cup&eacute;rables de la base de donn&eacute;es. Il n&rsquo;est donc pas recommand&eacute; d&rsquo;effectuer une r&eacute;cup&eacute;ration mat&eacute;rielle. Au lieu de cela, vous pouvez utiliser le logiciel de r&eacute;cup&eacute;ration Exchange pour r&eacute;parer la base de donn&eacute;es Exchange sans aucune perte de donn&eacute;es. Le logiciel r&eacute;cup&egrave;re &eacute;galement les messageries et les &eacute;l&eacute;ments de messagerie supprim&eacute;s accidentellement pendant la r&eacute;paration de la base de donn&eacute;es.<\/p><h2 class=\"wp-block-heading\" id=\"emplacement-du-fichier-de-la-base-de-donn&eacute;es-exchange\"><strong>Emplacement du fichier de la base de donn&eacute;es Exchange<\/strong><\/h2><p class=\"wp-block-paragraph\">Par d&eacute;faut, la base de donn&eacute;es est cr&eacute;&eacute;e &agrave; l&rsquo;emplacement suivant lors de l&rsquo;installation d&rsquo;Exchange.<\/p><pre class=\"wp-block-preformatted\"><code>C:\\Program Files\\Microsoft\\Exchange Server\\Vxx\\Mailbox\\&lt;database&gt;<\/code><\/pre><p class=\"wp-block-paragraph\">Ici, Vxx repr&eacute;sente la version d&rsquo;Exchange.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/exchnage-mailbox-location.png\" alt=\"Stellar\"><\/figure>\n<\/div><p class=\"wp-block-paragraph\">&Agrave; cet emplacement, outre le fichier de base de donn&eacute;es, les fichiers suivants sont stock&eacute;s,<\/p><ul class=\"wp-block-list\">\n<li><strong>Le fichier de la base de donn&eacute;es des messageries Exchange<\/strong><strong><\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Un fichier de base de donn&eacute;es Exchange (.EDB) stocke toutes les messageries et les donn&eacute;es sur le serveur. Vous pouvez modifier le nom ou l&rsquo;emplacement de la base de donn&eacute;es en utilisant Exchange Management Shell (EMS).<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/mailbox-edb.png\" alt=\"Stellar\"><\/figure>\n<\/div><ul class=\"wp-block-list\">\n<li><strong>Fichiers journaux<\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Un fichier journal, tel que E001.log, contient les enregistrements des transactions, qui sont effectu&eacute;es sur l&rsquo;&eacute;change.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/exchnage-edb-logs.png\" alt=\"Stellar\"><\/figure>\n<\/div><ul class=\"wp-block-list\">\n<li><strong>Fichier de point de contr&ocirc;le<\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Un fichier de point de contr&ocirc;le, tel que E001.chk, est utilis&eacute; par le serveur Exchange pour assurer le suivi de la relation entre la base de donn&eacute;es et les fichiers journaux.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/checkpoint-file.png\" alt=\"Stellar\"><\/figure>\n<\/div><ul class=\"wp-block-list\">\n<li><strong>Fichier journal r&eacute;serv&eacute;<\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Il s&rsquo;agit de fichiers au format .jrs, tels que E00res0001E.jrs, utilis&eacute;s par Exchange pour contenir les journaux de transactions lorsqu&rsquo;une situation, telle qu&rsquo;un disque plein, se produit. Il v&eacute;rifie l&rsquo;espace disque disponible avant de valider les modifications des fichiers journaux dans la base de donn&eacute;es.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/jrs-file-1.png\" alt=\"Stellar\"><\/figure>\n<\/div><ul class=\"wp-block-list\">\n<li><strong>Fichier journal temporaire&nbsp;<\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Un fichier journal temporaire, tel que E00tmo1.log, est utilis&eacute; lorsqu&rsquo;un nouveau fichier journal est cr&eacute;&eacute;.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/temporary-log-file-1.png\" alt=\"Stellar\"><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"commutateurs-eseutil\"><strong>Commutateurs EseUtil<\/strong><\/h2><p class=\"wp-block-paragraph\">Pour effectuer diff&eacute;rentes t&acirc;ches de maintenance et de r&eacute;paration Exchange sur une base de donn&eacute;es inaccessible, corrompue ou endommag&eacute;e, vous pouvez utiliser les commutateurs EseUtil suivants,<\/p><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Commutateur<\/strong><\/td><td><strong>Description<\/strong><\/td><\/tr><tr><td><strong>EseUtil \/D<\/strong><\/td><td>D&eacute;fragmente le fichier de la base de donn&eacute;es hors ligne. Aide &agrave; r&eacute;duire la taille globale de la base de donn&eacute;es Exchange sur le disque et optimise le fichier de la base de donn&eacute;es pour plus de performance. Permet &eacute;galement de v&eacute;rifier l&rsquo;&eacute;tat de sant&eacute; de la base de donn&eacute;es.<\/td><\/tr><tr><td><strong>EseUtil \/R<\/strong><\/td><td>Permet de restaurer la base de donn&eacute;es. Il reconstitue les fichiers du journal des transactions pour sortir la base de donn&eacute;es d&rsquo;un &eacute;tat d&rsquo;arr&ecirc;t non planifi&eacute; ou incoh&eacute;rent &agrave; un &eacute;tat d&rsquo;arr&ecirc;t propre ou coh&eacute;rent.<\/td><\/tr><tr><td><strong>EseUtil \/C<\/strong><\/td><td>Effectue une restauration mat&eacute;rielle et affiche les fichiers journaux de restauration de la base de donn&eacute;es.<\/td><\/tr><tr><td><strong>EseUtil \/M<\/strong><\/td><td>Il affiche les informations d&rsquo;en-t&ecirc;te des fichiers de base de donn&eacute;es, des fichiers journaux et des fichiers de point de contr&ocirc;le. Il montre &eacute;galement l&rsquo;allocation d&rsquo;espace de la base de donn&eacute;es et les informations d&rsquo;en-t&ecirc;te de page avec les m&eacute;tadonn&eacute;es.<\/td><\/tr><tr><td><strong>EseUtil \/P<\/strong><\/td><td>R&eacute;pare les bases de donn&eacute;es corrompues ou endommag&eacute;es. Il supprime les pages qui ne peuvent pas &ecirc;tre r&eacute;par&eacute;es. Cela peut entra&icirc;ner une perte de donn&eacute;es car il supprime le contenu gravement endommag&eacute; de la base de donn&eacute;es.<\/td><\/tr><tr><td><strong>EseUtil \/G<\/strong><\/td><td>Utilis&eacute; pour effectuer des contr&ocirc;les d&rsquo;int&eacute;grit&eacute;. Il v&eacute;rifie les contr&ocirc;les d&rsquo;int&eacute;grit&eacute; de la base de donn&eacute;es au niveau de la page et de l&rsquo;ESE afin de d&eacute;tecter des incoh&eacute;rences sp&eacute;cifiques &agrave; la base de donn&eacute;es.<\/td><\/tr><tr><td><strong>EseUtil \/Y<\/strong><\/td><td>Copie rapidement les fichiers volumineux tels que les fichiers de la base de donn&eacute;es des messageries.<\/td><\/tr><tr><td><strong>EseUtil \/K<\/strong><\/td><td>Effectue des tests de somme de contr&ocirc;le pour v&eacute;rifier les pages du fichier de base de donn&eacute;es, du fichier journal des transactions et du fichier de point de contr&ocirc;le.<\/td><\/tr><tr><td><strong>EseUtil \/MH<\/strong><\/td><td>Affiche l&rsquo;&eacute;tat de la base de donn&eacute;es, c&rsquo;est-&agrave;-dire arr&ecirc;t non planifi&eacute; (incoh&eacute;rent) ou arr&ecirc;t propre (coh&eacute;rent).<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading\" id=\"conditions-pr&eacute;alables-&agrave;-l&rsquo;ex&eacute;cution-d&rsquo;eseutil\"><strong>Conditions pr&eacute;alables &agrave; l&rsquo;ex&eacute;cution d&rsquo;EseUtil<\/strong><\/h2><p class=\"wp-block-paragraph\">Avant d&rsquo;ex&eacute;cuter EseUtil pour v&eacute;rifier, modifier ou r&eacute;parer les bases de donn&eacute;es Exchange, vous devez vous assurer des conditions pr&eacute;alables suivantes,<\/p><ol class=\"wp-block-list\" type=\"1\">\n<li>Sauvegarde du fichier de la base de donn&eacute;es Exchange<\/li>\n\n\n\n<li>Acc&egrave;s ou permissions de l&rsquo;administrateur<\/li>\n\n\n\n<li>Espace de stockage libre (au moins 1,2 fois la taille de la base de donn&eacute;es)<\/li>\n<\/ol><h2 class=\"wp-block-heading\" id=\"&Eacute;tapes-d&rsquo;utilisation-d&rsquo;eseutil-pour-la-r&eacute;paration-des-bases-de-donn&eacute;es-exchange\"><strong>&Eacute;tapes d&rsquo;utilisation d&rsquo;EseUtil pour la r&eacute;paration des bases de donn&eacute;es Exchange<\/strong><\/h2><p class=\"wp-block-paragraph\">Nous avons discut&eacute; ci-dessous des &eacute;tapes et des conditions requises pour utiliser EseUtil afin de r&eacute;parer la base de donn&eacute;es Exchange.<\/p><h3 class=\"wp-block-heading\" id=\"h-etape-1-localiser-eseutil\"><strong>&Eacute;tape 1 : Localiser EseUtil<\/strong><\/h3><p class=\"wp-block-paragraph\">Pour utiliser EseUtil, vous devez le trouver. Vous pouvez trouver l&rsquo;utilitaire EseUtil.exe dans le r&eacute;pertoire Bin de votre installation Exchange. Par exemple, si vous avez install&eacute; Exchange 2013 ou 2016 dans le volume du lecteur C:, vous pouvez localiser l&rsquo;EseUtil gr&acirc;ce au chemin d&rsquo;acc&egrave;s suivant,<\/p><pre class=\"wp-block-preformatted\"><code><em>C:\\Program Files\\Microsoft\\Exchange Server\\V15\\Bin<\/em>\\<\/code><\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/eseutil.exe-utility-1.png\" alt=\"Stellar\"><\/figure>\n<\/div><p class=\"wp-block-paragraph\">Apr&egrave;s avoir v&eacute;rifi&eacute; le chemin d&rsquo;acc&egrave;s, ouvrez l&rsquo;invite de commande en tant qu&rsquo;administrateur, puis modifiez le chemin d&rsquo;acc&egrave;s du r&eacute;pertoire &agrave; l&rsquo;emplacement d&rsquo;EseUtil en utilisant la commande suivante,<\/p><pre class=\"wp-block-preformatted\"><em><code>cd C:\\Program Files\\Microsoft\\Exchange Server\\V15\\Bin<\/code><\/em><\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/path-to-bin-folder-exchange.png\" alt=\"Stellar\"><\/figure>\n<\/div><p class=\"wp-block-paragraph\">Toutefois, si le chemin d&rsquo;acc&egrave;s &agrave; EseUtil est ajout&eacute; &agrave; la liste des variables d&rsquo;environnement, vous pouvez lancer l&rsquo;invite de commande directement &agrave; partir de n&rsquo;importe quel emplacement et ex&eacute;cuter les commandes EseUtil.<\/p><h3 class=\"wp-block-heading\" id=\"h-etape-2-verifier-la-taille-de-la-base-de-donnees\"><strong>&Eacute;tape 2 : V&eacute;rifier la taille de la base de donn&eacute;es<\/strong><\/h3><p class=\"wp-block-paragraph\">Si la taille de la base de donn&eacute;es est de 10 GB, ouvrez l&rsquo;ID d&rsquo;&eacute;v&eacute;nement 1221 pour v&eacute;rifier l&rsquo;espace blanc dans la base de donn&eacute;es. Une fois connu, soustrayez la taille de la base de donn&eacute;es des espaces blancs de la taille totale de la base de donn&eacute;es. C&rsquo;est l&rsquo;espace de stockage minimum requis pour utiliser EseUtil pour la r&eacute;paration de la base de donn&eacute;es Exchange.<\/p><h3 class=\"wp-block-heading\" id=\"h-etape-3-verifier-l-etat-de-la-base-de-donnees\"><strong>&Eacute;tape 3 : V&eacute;rifier l&rsquo;&eacute;tat de la base de donn&eacute;es<\/strong><\/h3><p class=\"wp-block-paragraph\">Pour identifier l&rsquo;&eacute;tat de la base de donn&eacute;es, utilisez le commutateur \/MH. Si l&rsquo;&eacute;tat affich&eacute; est Arr&ecirc;t propre, il ne devrait y avoir aucun probl&egrave;me et la base de donn&eacute;es peut &ecirc;tre facilement mont&eacute;e apr&egrave;s avoir d&eacute;plac&eacute; tous les fichiers journaux vers un autre emplacement.<\/p><p class=\"wp-block-paragraph\">Cependant, si la base de donn&eacute;es est dans l&rsquo;&eacute;tat <strong>Arr&ecirc;t non planifi&eacute;<\/strong>, la base de donn&eacute;es ne sera pas mont&eacute;e. Cela indique une base de donn&eacute;es incoh&eacute;rente ou corrompue. Cela peut se produire en raison de fichiers journaux manquants ou supprim&eacute;s et lorsque les fichiers journaux ne sont pas valid&eacute;s dans la base de donn&eacute;es.<\/p><p class=\"wp-block-paragraph\">La commande permettant de v&eacute;rifier la coh&eacute;rence ou l&rsquo;&eacute;tat de la base de donn&eacute;es est la suivante,<\/p><pre class=\"wp-block-preformatted\"><code>EseUtil \/mh &lt;nom du fichier de la base de donn&eacute;es&gt;<\/code><\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/dirty-shutdown.png\" alt=\"Stellar\"><\/figure>\n<\/div><h3 class=\"wp-block-heading\" id=\"h-etape-4-verifier-les-journaux\"><strong>&Eacute;tape 4 : V&eacute;rifier les journaux<\/strong><\/h3><p class=\"wp-block-paragraph\">Si votre base de donn&eacute;es est en Arr&ecirc;t non planifi&eacute;, vous verrez une autre ligne en dessous, qui mentionne le fichier journal qui est requis. L&rsquo;&eacute;tape suivante consiste &agrave; v&eacute;rifier si les journaux sont sains ou s&rsquo;il y a un probl&egrave;me avec les journaux. Pour ce faire, utilisez le pr&eacute;fixe ML avec EseUtil et le chemin d&rsquo;acc&egrave;s du journal que vous pouvez copier &agrave; partir de la section <em>journal requis<\/em> du rapport.<\/p><pre class=\"wp-block-preformatted\"><code>EseUtil \/ml \"M:\\mbx01\\logs\"<\/code><\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/exchange-logs.png\" alt=\"Stellar\"><\/figure>\n<\/div><p class=\"wp-block-paragraph\">Cela affichera l&rsquo;&eacute;tat des journaux. Si tous les journaux sont sains, vous obtiendrez le message suivant <em>&laquo;&nbsp;Aucun fichier journal endommag&eacute; n&rsquo;a &eacute;t&eacute; trouv&eacute;&nbsp;&raquo;<\/em>.<\/p><h3 class=\"wp-block-heading\" id=\"h-etape-5-effectuer-une-recuperation-logicielle\"><strong>&Eacute;tape 5 : Effectuer une r&eacute;cup&eacute;ration logicielle<\/strong><\/h3><p class=\"wp-block-paragraph\">Lorsque les journaux sont sains, vous pouvez effectuer une r&eacute;cup&eacute;ration logicielle en utilisant la commande&nbsp;<strong><em>EseUtil \/r&nbsp;<\/em>param&egrave;tre<\/strong>.<\/p><pre class=\"wp-block-preformatted\"><code>EseUtil \/r e00 \/l \"M:\\mbx01\\logs\" \/d \"M:\\mbx01\\database\"<\/code><\/pre><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/eseutil-soft-recovery.png\" alt=\"Stellar\"><\/figure>\n<\/div><p class=\"wp-block-paragraph\">Une fois ce processus termin&eacute;, vous pouvez rev&eacute;rifier l&rsquo;&eacute;tat de la base de donn&eacute;es &agrave; l&rsquo;aide de la commande <em>EseUtil \/mh<\/em>, puis monter la base de donn&eacute;es &agrave; l&rsquo;aide du cmdlet Mount-Database. Le processus de r&eacute;paration peut prendre un certain temps &agrave; se terminer, en fonction des dommages ou de la taille de la base de donn&eacute;es.<\/p><h3 class=\"wp-block-heading\" id=\"h-etape-6-effectuer-une-restauration-materielle\"><strong>&Eacute;tape 6 : Effectuer une restauration mat&eacute;rielle<\/strong><\/h3><p class=\"wp-block-paragraph\">Si vous obtenez toujours des erreurs et que la base de donn&eacute;es reste dans un <em>&eacute;tat d&rsquo;arr&ecirc;t non planifi&eacute;<\/em>, essayez alors de r&eacute;parer la base de donn&eacute;es via la r&eacute;cup&eacute;ration mat&eacute;rielle. Mais avant de le faire, vous devez savoir que ce processus de r&eacute;paration purgera toutes les donn&eacute;es qu&rsquo;EseUtil consid&egrave;re comme endommag&eacute;es. Vous devez prendre en compte et accepter la perte de donn&eacute;es qu&rsquo;entra&icirc;nera la r&eacute;cup&eacute;ration mat&eacute;rielle, quels que soient les dommages.<\/p><p class=\"wp-block-paragraph\">Pour ex&eacute;cuter la r&eacute;cup&eacute;ration mat&eacute;rielle, utilisez la commande <strong>EseUtil \/p<\/strong>. En plus d&rsquo;un espace de stockage suffisant pour traiter la base de donn&eacute;es, la r&eacute;cup&eacute;ration dure pourrait prendre un temps consid&eacute;rable. De plus, une fois que vous aurez d&eacute;marr&eacute;, un message vous rappellera les d&eacute;g&acirc;ts. Vous devez accepter l&rsquo;avertissement pour continuer et r&eacute;parer la base de donn&eacute;es Exchange via la r&eacute;cup&eacute;ration mat&eacute;rielle d&rsquo;EseUtil.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/hard-recovery-eseutil-warning.jpg\" alt=\"Stellar\"><figcaption class=\"wp-element-caption\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/integrity-check.png\" alt=\"Stellar\"><\/figcaption><\/figure>\n<\/div><p class=\"wp-block-paragraph\">Une fois cela fait, utilisez <strong>l&rsquo;outil IsInteg<\/strong> pour la r&eacute;paration de l&rsquo;index. IsInteg est un utilitaire de r&eacute;paration uniquement qui comprend la relation entre les tableaux et les enregistrements et les transforme en dossiers et en messages. L&rsquo;outil se trouve &agrave; l&rsquo;emplacement suivant,<\/p><pre class=\"wp-block-preformatted\"><code>C:&gt;Program Files&gt;Exchsrvr&gt; bin<\/code><\/pre><p class=\"wp-block-paragraph\">Ex&eacute;cutez ensuite le test IsInteg en utilisant la commande suivante,<\/p><pre class=\"wp-block-preformatted\"><code>Isinteg &ndash;s &lt;server_name&gt; -fix &ndash;test alltests<\/code><\/pre><p class=\"wp-block-paragraph\">Vous pouvez r&eacute;p&eacute;ter la commande plusieurs fois pour vous d&eacute;barrasser des erreurs. Une fois les erreurs corrig&eacute;es, vous pouvez monter la base de donn&eacute;es.<\/p><p class=\"wp-block-paragraph\">En outre, vous pouvez utiliser <em><strong><code>New-MailboxRepairRequest<\/code><\/strong><\/em>, si vous avez Exchange Server 2010 avec SP1 ou des versions ult&eacute;rieures, avant de monter la base de donn&eacute;es sur le serveur. Une derni&egrave;re chose, vous ne pouvez pas arr&ecirc;ter le processus une fois qu&rsquo;il a d&eacute;marr&eacute;. Si vous l&rsquo;arr&ecirc;tez quand m&ecirc;me, il peut causer encore plus de dommages &agrave; la base de donn&eacute;es. Cependant, si tout se passe bien, vous pourrez monter la base de donn&eacute;es.<\/p><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" class=\"apply-gradient-on-post-images\" src=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2020\/11\/new-mailboxrepairrequest-to-repair-exchange-database.png\" alt=\"Stellar\"><\/figure>\n<\/div><h2 class=\"wp-block-heading\" id=\"points-&agrave;-retenir-avant-d&rsquo;utiliser-eseutil-pour-la-r&eacute;paration-des-bases-de-donn&eacute;es-exchange\"><strong>Points &agrave; retenir avant d&rsquo;utiliser EseUtil pour la r&eacute;paration des bases de donn&eacute;es Exchange<\/strong><\/h2><p class=\"wp-block-paragraph\">Vous devez vous rappeler les points importants suivants avant d&rsquo;utiliser l&rsquo;EseUtil :<\/p><ol class=\"wp-block-list\" type=\"1\">\n<li>EseUtil n&rsquo;est pas un utilitaire infaillible. Il peut &eacute;chouer et causer plus de dommages ou de pertes de donn&eacute;es en fonction de la m&eacute;thode de r&eacute;cup&eacute;ration que vous choisissez et du niveau de corruption de la base de donn&eacute;es.<\/li>\n\n\n\n<li>Il n&rsquo;est pas n&eacute;cessaire que vous soyez en mesure de monter la base de donn&eacute;es apr&egrave;s la r&eacute;cup&eacute;ration.<\/li>\n\n\n\n<li>En fonction de la taille de la base de donn&eacute;es et du niveau de dommage, vos utilisateurs ne pourront pas recevoir, envoyer ou travailler avec leurs messageries pendant le processus de r&eacute;paration de la base de donn&eacute;es EseUtil. Cela pourrait entra&icirc;ner une interruption pendant plusieurs heures et causer des dommages &agrave; l&rsquo;entreprise.<\/li>\n<\/ol><p class=\"wp-block-paragraph\">Vous pouvez &eacute;galement utiliser <em>Stellar Repair for Exchange<\/em> pour effectuer le travail sans effort et en beaucoup moins de temps. L&rsquo;application peut ouvrir un fichier EDB corrompu &agrave; partir de n&rsquo;importe quelle version d&rsquo;Exchange Server. Vous pouvez ensuite r&eacute;parer la base de donn&eacute;es. Elle vous permet &eacute;galement d&rsquo;effectuer une recherche granulaire avec des filtres de recherche.<\/p><p style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/UvvRFqdvvI0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p><p class=\"wp-block-paragraph\">Le logiciel permet d&rsquo;extraire les messageries et de les enregistrer au format PST lorsque la base de donn&eacute;es est endommag&eacute;e sans qu&rsquo;il soit possible de la r&eacute;parer. Cela peut aider &agrave; &eacute;viter les temps d&rsquo;arr&ecirc;t et &agrave; restaurer les messageries des utilisateurs afin que les affaires puissent continuer. Vous pouvez &eacute;galement utiliser ce <a href=\"https:\/\/www.stellarinfo.com\/fr\/logiciel-recuperation-e-mail-exchange-ebd.php\">logiciel de r&eacute;cup&eacute;ration EDB<\/a> pour importer les messageries d&rsquo;un fichier EDB directement dans une base de donn&eacute;es Exchange Server active avec une option de correspondance automatique des messageries.<\/p><p class=\"wp-block-paragraph\">Outre les fichiers PST, Stellar Repair for Exchange peut &eacute;galement exporter des messageries et des &eacute;l&eacute;ments de messageries vers d&rsquo;autres formats de fichiers, tels que EML, PDF, MSG, HTML &amp; RTF, et directement vers un compte Office 365.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La r&eacute;cup&eacute;ration de la base de donn&eacute;es Exchange (EDB) est souvent n&eacute;cessaire&hellip; <a class=\"more-link\" href=\"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/\">Continue reading <span class=\"screen-reader-text\">Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":80776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1265],"tags":[1913,1914],"class_list":["post-80770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recuperation-exchange","tag-comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange","tag-eseutil-pour-la-reparation-des-bases-de-donnees-exchange","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?<\/title>\n<meta name=\"description\" content=\"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s&#039;agit d&#039;un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l&#039;int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\" \/>\n<meta property=\"og:description\" content=\"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s&#039;agit d&#039;un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l&#039;int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/\" \/>\n<meta property=\"og:site_name\" content=\"Stellar Data Recovery Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-28T08:41:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T03:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eric Simson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eric Simson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/\"},\"author\":{\"name\":\"Eric Simson\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b4823430443e4bb02f48d6dfaad50f89\"},\"headline\":\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\",\"datePublished\":\"2021-05-28T08:41:58+00:00\",\"dateModified\":\"2023-04-20T03:32:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/\"},\"wordCount\":2306,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg\",\"keywords\":[\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\",\"EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange\"],\"articleSection\":[\"R\u00e9cup\u00e9ration Exchange\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/\",\"url\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/\",\"name\":\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg\",\"datePublished\":\"2021-05-28T08:41:58+00:00\",\"dateModified\":\"2023-04-20T03:32:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b4823430443e4bb02f48d6dfaad50f89\"},\"description\":\"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s'agit d'un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l'int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg\",\"contentUrl\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg\",\"width\":1000,\"height\":600,\"caption\":\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/fr\\\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/\",\"name\":\"Stellar Data Recovery Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/#\\\/schema\\\/person\\\/b4823430443e4bb02f48d6dfaad50f89\",\"name\":\"Eric Simson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g\",\"caption\":\"Eric Simson\"},\"description\":\"Eric Simson is an Email Platform Consultant and is associated with Stellar Data Recovery from last 6 years. He writes about the latest technology tips and provides custom solutions related to MS Outlook, MS Exchange Server, Office 365, and many other Email Clients &amp; Servers.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/eric-simson-30bb8222a\\\/\"],\"url\":\"https:\\\/\\\/www.stellarinfo.com\\\/blog\\\/author\\\/priyal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?","description":"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s'agit d'un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l'int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/","og_locale":"en_US","og_type":"article","og_title":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?","og_description":"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s'agit d'un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l'int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.","og_url":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/","og_site_name":"Stellar Data Recovery Blog","article_published_time":"2021-05-28T08:41:58+00:00","article_modified_time":"2023-04-20T03:32:25+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg","type":"image\/jpeg"}],"author":"Eric Simson","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eric Simson","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#article","isPartOf":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/"},"author":{"name":"Eric Simson","@id":"https:\/\/www.stellarinfo.com\/blog\/#\/schema\/person\/b4823430443e4bb02f48d6dfaad50f89"},"headline":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?","datePublished":"2021-05-28T08:41:58+00:00","dateModified":"2023-04-20T03:32:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/"},"wordCount":2306,"commentCount":0,"image":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg","keywords":["Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?","EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange"],"articleSection":["R\u00e9cup\u00e9ration Exchange"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/","url":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/","name":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ? Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?","isPartOf":{"@id":"https:\/\/www.stellarinfo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#primaryimage"},"image":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg","datePublished":"2021-05-28T08:41:58+00:00","dateModified":"2023-04-20T03:32:25+00:00","author":{"@id":"https:\/\/www.stellarinfo.com\/blog\/#\/schema\/person\/b4823430443e4bb02f48d6dfaad50f89"},"description":"Extensible Storage Engine Utilities ou EseUtil est un outil en ligne de commande qui est utilis\u00e9 pour r\u00e9soudre les probl\u00e8mes caus\u00e9s par la corruption des bases de donn\u00e9es. Il s'agit d'un outil Exchange tr\u00e8s utile pour les administrateurs car il les aide \u00e0 effectuer diverses t\u00e2ches de maintenance et de r\u00e9paration des bases de donn\u00e9es Exchange, telles que la v\u00e9rification de l'int\u00e9grit\u00e9 de la base de donn\u00e9es, la d\u00e9fragmentation, la r\u00e9duction de la taille de la base de donn\u00e9es et la r\u00e9paration ou la r\u00e9cup\u00e9ration de fichiers de base de donn\u00e9es corrompus.","breadcrumb":{"@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#primaryimage","url":"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg","contentUrl":"https:\/\/www.stellarinfo.com\/blog\/wp-content\/uploads\/2021\/05\/FR-Comment-utiliser-EseUtil-pour-la-reparation-des-bases-de-donnees-Exchange.jpg","width":1000,"height":600,"caption":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.stellarinfo.com\/blog\/fr\/comment-utiliser-eseutil-pour-la-reparation-des-bases-de-donnees-exchange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stellarinfo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Comment utiliser EseUtil pour la r\u00e9paration des bases de donn\u00e9es Exchange ?"}]},{"@type":"WebSite","@id":"https:\/\/www.stellarinfo.com\/blog\/#website","url":"https:\/\/www.stellarinfo.com\/blog\/","name":"Stellar Data Recovery Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stellarinfo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.stellarinfo.com\/blog\/#\/schema\/person\/b4823430443e4bb02f48d6dfaad50f89","name":"Eric Simson","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/944393a40609b2d087c131b021f96dda56d23e694371e0b73b29dbd86851ffe2?s=96&d=mm&r=g","caption":"Eric Simson"},"description":"Eric Simson is an Email Platform Consultant and is associated with Stellar Data Recovery from last 6 years. He writes about the latest technology tips and provides custom solutions related to MS Outlook, MS Exchange Server, Office 365, and many other Email Clients &amp; Servers.","sameAs":["https:\/\/www.linkedin.com\/in\/eric-simson-30bb8222a\/"],"url":"https:\/\/www.stellarinfo.com\/blog\/author\/priyal\/"}]}},"_links":{"self":[{"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/posts\/80770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/comments?post=80770"}],"version-history":[{"count":7,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/posts\/80770\/revisions"}],"predecessor-version":[{"id":131912,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/posts\/80770\/revisions\/131912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/media\/80776"}],"wp:attachment":[{"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/media?parent=80770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/categories?post=80770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stellarinfo.com\/blog\/wp-json\/wp\/v2\/tags?post=80770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}